{"id":6107,"date":"2020-08-17T14:06:40","date_gmt":"2020-08-17T12:06:40","guid":{"rendered":"https:\/\/app.lib.uliege.be\/guide_catalo\/?p=6107"},"modified":"2023-03-03T14:21:11","modified_gmt":"2023-03-03T13:21:11","slug":"nouvel-editeur-de-metadonnees-quoi-de-neuf","status":"publish","type":"post","link":"https:\/\/services.lib.uliege.be\/guide_catalo\/nouvel-editeur-de-metadonnees-quoi-de-neuf\/","title":{"rendered":"Nouvel \u00e9diteur de m\u00e9tadonn\u00e9es : quoi de neuf ?"},"content":{"rendered":"\n<p><strong>Derni\u00e8re mise \u00e0 jour le 17-08-2020<\/strong><\/p>\n\n\n\n<p>Suite \u00e0 l&rsquo;article concernant le <a href=\"https:\/\/services.lib.uliege.be\/guide_catalo\/nouvel-editeur-de-metadonnees\/\">nouvel \u00e9diteur de m\u00e9tadonn\u00e9es<\/a>, voici un aper\u00e7u de la mise en place progressive des fonctionnalit\u00e9s.<\/p>\n\n\n\n<p>Pour rappel, le nouvel \u00e9diteur de m\u00e9tadonn\u00e9es (dans sa version en construction) est visible dans la <a rel=\"noreferrer noopener\" href=\"https:\/\/sandbox-eu.alma.exlibrisgroup.com\/mng\/login?institute=32ULG_INST&amp;auth=local\" target=\"_blank\">sandbox<\/a>.<br>En septembre, il sera propos\u00e9 dans l&rsquo;environnement de production, mais seule la partie Gestion des notices sera accessible.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">La <em>mise \u00e0 jour du mois d&rsquo;ao\u00fbt<\/em> apporte notamment l&rsquo;ajout des fonctionnalit\u00e9s suivantes :<\/h5>\n\n\n\n<ul class=\"wp-block-list\"><li>Menu <em>Record Actions<\/em> :<ul><li>Assign Record to Another Cataloger (anc. menu <em>File<\/em>)<\/li><li>Suppress from Discovery (anc. menu <em>Tools<\/em> <em>&gt; Set Management Tags<\/em>)<\/li><li>Delete Record (anc. menu <em>File<\/em>)<\/li><\/ul><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"671\" height=\"549\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/07\/NMDE_news_08_1.png\" alt=\"\" class=\"wp-image-6111\" srcset=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/07\/NMDE_news_08_1.png 671w, https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/07\/NMDE_news_08_1-300x245.png 300w\" sizes=\"auto, (max-width: 671px) 100vw, 671px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li>Menu <em>View Related Data<\/em> :<ul><li>View in Search (anc. menu <em>Tools &gt; MARC bibliographic<\/em>)<\/li><\/ul><\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"813\" height=\"404\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/07\/NMDE_news_08_2.png\" alt=\"\" class=\"wp-image-6112\" srcset=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/07\/NMDE_news_08_2.png 813w, https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/07\/NMDE_news_08_2-300x149.png 300w, https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/07\/NMDE_news_08_2-768x382.png 768w\" sizes=\"auto, (max-width: 813px) 100vw, 813px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\"><li>Catalogage des sets<\/li><\/ul>\n\n\n\n<p>\u00c0 partir de la page Manage Sets, vous pouvez envoyer un set de notices dans l&rsquo;\u00e9diteur de m\u00e9tadonn\u00e9es pour en \u00e9diter les notices.<br>Cette action est disponible pour les sets All titles et Physical titles, ainsi que pour les portfolios locaux (Electronic titles). <br>La limite est de 200 notices.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image.png\" alt=\"\" class=\"wp-image-6118\" width=\"644\" height=\"305\"\/><\/figure><\/div>\n\n\n\n<p>Le set ajout\u00e9 \u00e0 l&rsquo;\u00e9diteur de m\u00e9tadonn\u00e9es est visible dans les onglets du haut :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image-3.png\" alt=\"\" class=\"wp-image-6121\"\/><\/figure><\/div>\n\n\n\n<p>Vous pouvez ajouter plusieurs sets.<br>Cliquez sur Records List pour ouvrir la liste des sets<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image-4.png\" alt=\"\" class=\"wp-image-6122\"\/><\/figure>\n\n\n\n<p>Cliquez sur le set \u00e0 traiter pour visualiser la liste des notices : <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image-5.png\" alt=\"\" class=\"wp-image-6123\" width=\"234\" height=\"350\"\/><\/figure><\/div>\n\n\n\n<p>Cliquez ensuite sur la notice que vous voulez ouvrir pour modification. Cette notice s&rsquo;affiche alors en gras dans la liste : <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image-6.png\" alt=\"\" class=\"wp-image-6124\" width=\"518\" height=\"258\"\/><\/figure><\/div>\n\n\n\n<p>La notice en cours d&rsquo;\u00e9dition est identifi\u00e9e comme faisant partie d&rsquo;un set :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image-7.png\" alt=\"\" class=\"wp-image-6125\" width=\"529\" height=\"313\"\/><\/figure><\/div>\n\n\n\n<p>Une fois la notice d\u00e9bloqu\u00e9e (Release record), elle est supprim\u00e9e de la liste :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image-9.png\" alt=\"\" class=\"wp-image-6127\"\/><figcaption>Il reste donc 9 notices \u00e0 traiter sur les 10 que contient le set.<\/figcaption><\/figure><\/div>\n\n\n\n<p><em>Attention ! Si vous retirez des notices d&rsquo;un set exemplaris\u00e9 (itemized), le contenu du set n&rsquo;est pas mis \u00e0 jour dans l&rsquo;\u00e9diteur de m\u00e9tadonn\u00e9es.<\/em><\/p>\n\n\n\n<p>La fonctionnalit\u00e9 de recherche est \u00e9galement possible sur les sets : <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image-10.png\" alt=\"\" class=\"wp-image-6132\"\/><\/figure>\n\n\n\n<p>La recherche r\u00e9duit le nombre de sets en fonction du r\u00e9sultat : <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image-11.png\" alt=\"\" class=\"wp-image-6133\"\/><\/figure><\/div>\n\n\n\n<p>Lorsqu&rsquo;on ouvre le contenu du set, seules les notices correspondant au crit\u00e8re de recherche sont visibles :<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"288\" height=\"276\" src=\"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-content\/uploads\/2020\/08\/image-12.png\" alt=\"\" class=\"wp-image-6134\"\/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Derni\u00e8re mise \u00e0 jour le 17-08-2020 Suite \u00e0 l&rsquo;article concernant le nouvel \u00e9diteur de m\u00e9tadonn\u00e9es, voici un aper\u00e7u de la mise en place progressive des&hellip;<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[77],"tags":[],"class_list":["post-6107","post","type-post","status-publish","format-standard","hentry","category-obsolete"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/posts\/6107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/comments?post=6107"}],"version-history":[{"count":11,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/posts\/6107\/revisions"}],"predecessor-version":[{"id":6138,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/posts\/6107\/revisions\/6138"}],"wp:attachment":[{"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/media?parent=6107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/categories?post=6107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/tags?post=6107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}