{"id":1615,"date":"2020-01-10T10:52:02","date_gmt":"2020-01-10T09:52:02","guid":{"rendered":"https:\/\/app.lib.uliege.be\/guide_catalo\/?p=1615"},"modified":"2025-11-13T16:01:29","modified_gmt":"2025-11-13T15:01:29","slug":"909-hol","status":"publish","type":"post","link":"https:\/\/services.lib.uliege.be\/guide_catalo\/909-hol\/","title":{"rendered":"Zone 909 &#8211; M\u00e9thode d\u2019acquisition &#8211; Donn\u00e9es ALEPH (NR) [HOL]"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_76 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">Table des mati\u00e8res<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/services.lib.uliege.be\/guide_catalo\/909-hol\/#Application\" >Application<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/services.lib.uliege.be\/guide_catalo\/909-hol\/#Exploitation_de_la_zone\" >Exploitation de la zone<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Le champ 909 est un champ local issu du champ local 009 qui \u00e9tait utilis\u00e9 dans notre SIGB ALEPH500 avant le passage \u00e0 Alma en f\u00e9vrier 2015. Ce champ 009 permettait d&rsquo;indiquer, au niveau de la notice de donn\u00e9es  sur les fonds, la m\u00e9thode d\u2019acquisition du document catalogu\u00e9.  <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Application\"><\/span>Application<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>Il ne doit plus \u00eatre utilis\u00e9 dans les nouvelles notices de fonds (monographies ou p\u00e9riodiques), les m\u00e9thodes d&rsquo;acquisitions \u00e9tant renseign\u00e9es par d&rsquo;autres \u00e9l\u00e9ments (voir la page <a href=\"https:\/\/services.lib.uliege.be\/guide_catalo\/workflow-traitement-des-ressources-passer-ou-non-par-les-acquisitions\/\">Workflow traitement des ressources &#8211; passer ou non par les Acquisitions)<\/a><br><br>Ne pas confondre ce champ avec le champ <a href=\"https:\/\/services.lib.uliege.be\/guide_catalo\/zone-541-note-sur-la-source-immediate-dacquisition-r\/\">541<\/a>, qui est r\u00e9serv\u00e9 aux documents rares et aux ensembles remarquables.<\/p>\n\n\n\n<p>Le champ 541 fait partie de l\u2019histoire du document, puisqu&rsquo;il mentionne la source imm\u00e9diate de l\u2019acquisition, g\u00e9n\u00e9ralement en suite \u00e0 une succession identifi\u00e9e ou non de provenances diverses.<\/p>\n\n\n\n<p>Ainsi, le champ 541 peut \u00eatre affich\u00e9 dans le catalogue public, \u00e0 l\u2019inverse des autres zones qui permettent de renseigner une m\u00e9thode d&rsquo;acquisition et qui servent essentiellement \u00e0 la gestion interne des collections.  <\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Exploitation_de_la_zone\"><\/span>Exploitation de la zone<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p><em><strong>Indexation<\/strong><\/em> <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Alma <\/strong>: index Mode Acq (HOL 909), recherche Titres physiques ou Exemplaires physiques <\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le champ 909 est un champ local issu du champ local 009 qui \u00e9tait utilis\u00e9 dans notre SIGB ALEPH500 avant le passage \u00e0 Alma en&hellip;<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-1615","post","type-post","status-publish","format-standard","hentry","category-donnees-sur-les-fonds"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/posts\/1615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/comments?post=1615"}],"version-history":[{"count":6,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/posts\/1615\/revisions"}],"predecessor-version":[{"id":12787,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/posts\/1615\/revisions\/12787"}],"wp:attachment":[{"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/media?parent=1615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/categories?post=1615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/services.lib.uliege.be\/guide_catalo\/wp-json\/wp\/v2\/tags?post=1615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}